{"id":4147,"date":"2024-11-07T10:44:25","date_gmt":"2024-11-07T01:44:25","guid":{"rendered":"http:\/\/www.chemistry.titech.ac.jp\/?post_type=event&#038;p=4147"},"modified":"2024-11-07T10:44:25","modified_gmt":"2024-11-07T01:44:25","slug":"%e5%bc%b7%e3%83%ac%e3%83%bc%e3%82%b6%e3%83%bc%e5%a0%b4%e5%8e%9f%e5%ad%90%e5%88%86%e5%ad%90%e9%81%8e%e7%a8%8b%e3%81%ae%e5%9f%ba%e7%a4%8e%e3%80%90%e5%8c%96%e5%ad%a6%e7%89%b9%e5%88%a5%e8%ac%9b%e7%be%a9","status":"publish","type":"event","link":"http:\/\/www.chemistry.titech.ac.jp\/en\/event\/%e5%bc%b7%e3%83%ac%e3%83%bc%e3%82%b6%e3%83%bc%e5%a0%b4%e5%8e%9f%e5%ad%90%e5%88%86%e5%ad%90%e9%81%8e%e7%a8%8b%e3%81%ae%e5%9f%ba%e7%a4%8e%e3%80%90%e5%8c%96%e5%ad%a6%e7%89%b9%e5%88%a5%e8%ac%9b%e7%be%a9\/","title":{"rendered":"\u5f37\u30ec\u30fc\u30b6\u30fc\u5834\u539f\u5b50\u5206\u5b50\u904e\u7a0b\u306e\u57fa\u790e\u3010\u5316\u5b66\u7279\u5225\u8b1b\u7fa9\u7b2c\u4e94\u3011"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","event_taxonomy":[5],"class_list":["post-4147","event","type-event","status-publish","hentry","event_taxonomy-intensive"],"acf":[],"_links":{"self":[{"href":"http:\/\/www.chemistry.titech.ac.jp\/en\/wp-json\/wp\/v2\/event\/4147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.chemistry.titech.ac.jp\/en\/wp-json\/wp\/v2\/event"}],"about":[{"href":"http:\/\/www.chemistry.titech.ac.jp\/en\/wp-json\/wp\/v2\/types\/event"}],"wp:attachment":[{"href":"http:\/\/www.chemistry.titech.ac.jp\/en\/wp-json\/wp\/v2\/media?parent=4147"}],"wp:term":[{"taxonomy":"event_taxonomy","embeddable":true,"href":"http:\/\/www.chemistry.titech.ac.jp\/en\/wp-json\/wp\/v2\/event_taxonomy?post=4147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}